{"id":13424,"date":"2024-02-01T13:00:53","date_gmt":"2024-02-01T12:00:53","guid":{"rendered":"https:\/\/pibgroupiberia.com\/?p=3410"},"modified":"2026-05-27T12:31:12","modified_gmt":"2026-05-27T10:31:12","slug":"posso-mentir-num-questionario-de-seguro-de-saude-ou-de-vida","status":"publish","type":"post","link":"https:\/\/pibgroupiberia.com\/pt\/blog\/puedo-mentir-en-el-cuestionario-de-un-seguro-de-salud-o-vida\/","title":{"rendered":"O que acontece se eu mentir ao seguro de sa\u00fade?"},"content":{"rendered":"<p>Para contratar um <a href=\"\/pt\/individuos\/solucoes-de-seguros-para-particulares\/seguro-de-saude\/\">seguro de sa\u00fade<\/a>\u00a0ou um seguro de vida, deve preencher-se um <strong>question\u00e1rio m\u00e9dico.<\/strong> Em cada empresa, estas quest\u00f5es s\u00e3o diferentes, uma vez que a pessoa que as coloca \u00e9 a <strong>departamento jur\u00eddico de cada<\/strong>. A quest\u00e3o coloca-se frequentemente: <em>\u201cPonho isto?\u201d<\/em>. Vamos falar sobre isso.<\/p>\n<h2>O que \u00e9 que as companhias de seguros procuram quando preenchem um question\u00e1rio m\u00e9dico?<\/h2>\n<p>As companhias de seguros est\u00e3o a levar muito a s\u00e9rio os question\u00e1rios m\u00e9dicos. No passado, havia uma grande margem de manobra em muitas quest\u00f5es, devido a numerosos problemas com os <strong>fraude no sector dos seguros<\/strong> e melhorando as suas auditorias internas e externas, t\u00eam sido <strong>refor\u00e7ou estes requisitos<\/strong>:<\/p>\n<ul>\n<li>Os question\u00e1rios m\u00e9dicos s\u00e3o mais extensos.<\/li>\n<li>O or\u00e7amento foi aumentado para o pessoal m\u00e9dico que avalia os question\u00e1rios.<\/li>\n<\/ul>\n<p>A resposta l\u00f3gica \u00e0 pergunta do t\u00edtulo deste artigo \u00e9 que n\u00e3o devemos mentir \u00e0 seguradora de sa\u00fade. No entanto, deve ficar claro que n\u00e3o se trata de refletir quest\u00f5es irrelevantes ou de responder a perguntas que n\u00e3o s\u00e3o explicitamente colocadas. <span style=\"font-size: inherit;\">A maior parte dos question\u00e1rios perguntava sobre <\/span><strong style=\"font-size: inherit;\">doen\u00e7as \u00abdiagnosticadas\u00bb.<\/strong><\/p>\n<blockquote><p><em>Isto significa, por exemplo, que se tivermos um ligeiro desconforto no tornozelo e n\u00e3o tivermos quaisquer testes marcados para um futuro pr\u00f3ximo, exceto para perguntas expl\u00edcitas que questionem esse mesmo aspeto, tal n\u00e3o ter\u00e1 de ser declarado.<\/em><\/p><\/blockquote>\n<p>Diferente \u00e9 a pessoa que tem problemas com diabetes, ou problemas de imunodefici\u00eancia, em geral, doen\u00e7as diagnosticadas ou cirurgias recentes. Todos estes aspectos devem constar do question\u00e1rio, sempre que forem inquiridos.<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-27177\" src=\"\/wp-content\/uploads\/2017\/01\/cuestionario-seguro-de-vida.jpg\" alt=\"Fui expulso do meu seguro de sa\u00fade \" width=\"949\" height=\"632\" \/><\/strong><\/p>\n<h2>Porqu\u00ea N\u00c3O mentir no question\u00e1rio m\u00e9dico?<\/h2>\n<p>Discutimos este assunto com os respons\u00e1veis m\u00e9dicos de muitas companhias de seguros. No <strong>pol\u00edticas de sa\u00fade<\/strong>, Para certos testes de diagn\u00f3stico, cirurgias e outros problemas, precisamos de ter <strong>autoriza\u00e7\u00e3o da empresa.<\/strong><\/p>\n<p>Se tivermos acabado de subscrever a nossa ap\u00f3lice e, em menos de um ano ou dois anos, tivermos de ser operados, a companhia ir\u00e1 falar com o especialista que aconselhou a opera\u00e7\u00e3o, para lhe perguntar sobre o historial do doente.<\/p>\n<p><strong>Se as declara\u00e7\u00f5es constantes do question\u00e1rio m\u00e9dico forem consideradas falsas, a companhia n\u00e3o assumir\u00e1 a opera\u00e7\u00e3o.<\/strong> e isso pode ter duas consequ\u00eancias para n\u00f3s:<\/p>\n<ol>\n<li>Imposi\u00e7\u00e3o de um <strong>exclus\u00e3o nos seguros<\/strong> em rela\u00e7\u00e3o a esta doen\u00e7a.<\/li>\n<li><strong>Cancelar a ap\u00f3lice<\/strong> diretamente em fun\u00e7\u00e3o da gravidade da n\u00e3o declara\u00e7\u00e3o.<\/li>\n<\/ol>\n<p>\u00c9 mais grave <strong>se nos referirmos ao seguro de vida<\/strong>. Se estivermos a cobrir um capital em caso de morte ou invalidez e, de repente, ocorrer um destes imprevistos:<\/p>\n<blockquote><p><em>A empresa s\u00f3 pagar\u00e1 se, depois de averiguar a raz\u00e3o do sucedido e de cruzar o question\u00e1rio, detetar que tudo foi verdadeiro e sem oculta\u00e7\u00e3o de qualquer historial m\u00e9dico.<\/em><\/p><\/blockquote>\n<p>Caso contr\u00e1rio, os problemas podem ser muito graves, conduzindo n\u00e3o s\u00f3 a atrasos de pagamento, mas tamb\u00e9m \u00e0 aus\u00eancia de pagamento. Decidimos escrever este artigo porque lemos sobre estas quest\u00f5es na imprensa e vemo-las diariamente, e s\u00e3o quest\u00f5es muito s\u00e9rias.<\/p>\n<h2>A nossa recomenda\u00e7\u00e3o para o question\u00e1rio<\/h2>\n<p>\u00c9 melhor <strong>ser honesto<\/strong> nas respostas ao question\u00e1rio. Deixamos ent\u00e3o ao corretor a tarefa de negociar com a empresa para evitar exclus\u00f5es, uma vez que tem mais poder sobre ela.<\/p>\n<p>Se pretende uma corretora com uma rela\u00e7\u00e3o pr\u00f3xima com as companhias de seguros, para evitar problemas futuros, contacte-nos.<strong>.\u00a0<\/strong>Se quiser saber mais sobre seguros<strong> seguro de vida ou de sa\u00fade<\/strong>, Ajudamo-lo em tudo o que precisar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os question\u00e1rios de seguros s\u00e3o cada vez mais longos, pelo que temos de saber como responder-lhes.<\/p>","protected":false},"author":14,"featured_media":13425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":5,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"CreativeWorkSeries","footnotes":""},"categories":[16,152],"tags":[165],"class_list":["post-13424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulares","category-profesionales","tag-vida"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/13424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/comments?post=13424"}],"version-history":[{"count":0,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/13424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media\/13425"}],"wp:attachment":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media?parent=13424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/categories?post=13424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/tags?post=13424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}