{"id":13755,"date":"2023-07-24T08:18:56","date_gmt":"2023-07-24T06:18:56","guid":{"rendered":"https:\/\/pibgroupiberia.com\/?p=55036"},"modified":"2026-05-27T12:29:20","modified_gmt":"2026-05-27T10:29:20","slug":"periodo-de-diferimento","status":"publish","type":"post","link":"https:\/\/pibgroupiberia.com\/pt\/blog\/periodo-carencia\/","title":{"rendered":"O que \u00e9 o per\u00edodo de espera do seguro de doen\u00e7a e em que consiste?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Alguma vez vos aconteceu que <\/span><b>n\u00e3o p\u00f4de aceder a determinados servi\u00e7os m\u00e9dicos, apesar de ter contra\u00eddo um contrato de seguro de doen\u00e7a <a href=\"\/pt\/individuos\/solucoes-de-seguros-para-particulares\/seguro-de-saude\/\">seguro de sa\u00fade<\/a><\/b><span style=\"font-weight: 400;\">, porque tinha per\u00edodos de espera? \u00c9 uma situa\u00e7\u00e3o que pode ser frustrante e preocupante quando se necessita de cuidados m\u00e9dicos especializados ou de um tratamento espec\u00edfico com car\u00e1cter de urg\u00eancia. \u00c9 certo que a espera pode provocar ansiedade e fazer com que duvide se escolheu a ap\u00f3lice adequada \u00e0s suas necessidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O per\u00edodo de car\u00eancia nos seguros de sa\u00fade \u00e9 um termo que suscita frequentemente muitas d\u00favidas e preocupa\u00e7\u00f5es entre os segurados. Felizmente, <\/span><b>v\u00e1rias companhias de seguros est\u00e3o a implementar esquemas inovadores para oferecer uma cobertura mais r\u00e1pida e mais acess\u00edvel<\/b><span style=\"font-weight: 400;\"> aos seus clientes. Se leu o nosso artigo sobre <\/span><a href=\"https:\/\/pibgroupiberia.com\/pt\/blogue\/seguro-de-saude-e-tudo-o-que-e-necessario-sem-periodo-de-espera\/\"><span style=\"font-weight: 400;\">seguros de sa\u00fade e campanhas sem per\u00edodo de espera<\/span><\/a><span style=\"font-weight: 400;\">, Se assim for, talvez queiras ir um pouco mais fundo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesta ocasi\u00e3o, o Grupo PIB Ib\u00e9ria vai ajud\u00e1-lo a conhecer em profundidade <\/span><b>o que \u00e9 o per\u00edodo de car\u00eancia e como funciona no seu seguro de sa\u00fade?<\/b><span style=\"font-weight: 400;\">, Isto ajud\u00e1-lo-\u00e1 a planear melhor os seus cuidados m\u00e9dicos e a estar preparado para qualquer imprevisto.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Qual \u00e9 o per\u00edodo de espera?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O per\u00edodo de car\u00eancia \u00e9 o intervalo de tempo estabelecido por uma companhia de seguros. <\/span><b>durante o qual o segurado n\u00e3o pode recorrer a determinados servi\u00e7os ou coberturas<\/b><span style=\"font-weight: 400;\"> inclu\u00eddo na sua ap\u00f3lice. Trata-se, portanto, de um per\u00edodo de car\u00eancia que come\u00e7a a contar a partir da entrada em vigor do contrato de seguro de doen\u00e7a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isto n\u00e3o significa que, a partir do momento em que o seguro de doen\u00e7a \u00e9 subscrito, n\u00e3o possa ser utilizado, mas apenas para determinados servi\u00e7os, como interven\u00e7\u00f5es cir\u00fargicas, em que \u00e9 necess\u00e1rio esperar alguns meses para poder utilizar o seguro.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que significa o per\u00edodo de car\u00eancia no seguro de doen\u00e7a?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A subscri\u00e7\u00e3o de um seguro de sa\u00fade pode proteg\u00ea-lo de qualquer acidente m\u00e9dico que possa sofrer, mas deve ter em conta que<\/span><b> este tipo de ap\u00f3lice nem sempre cobre todos os casos desde o primeiro dia.<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">O seu seguro de doen\u00e7a inclui per\u00edodos de car\u00eancia? Nesse caso, ter\u00e1 de esperar um determinado per\u00edodo de tempo se quiser usufruir de todas as garantias do seu seguro. Sabe porqu\u00ea?<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">No mundo dos seguros de sa\u00fade, muitos clientes tendem a inscrever-se em determinadas companhias apenas para resolver problemas ou necessidades de sa\u00fade espec\u00edficos e, uma vez resolvidos, voltam a cancelar a sua inscri\u00e7\u00e3o. Para evitar esta situa\u00e7\u00e3o, as seguradoras tentam incluir per\u00edodos de car\u00eancia nos seus servi\u00e7os como forma de evitar este tipo de problemas.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Quais s\u00e3o os per\u00edodos de espera no dom\u00ednio da sa\u00fade?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Os per\u00edodos de car\u00eancia nos contratos de seguro de doen\u00e7a podem variar consoante a empresa e o tipo de servi\u00e7o. No entanto, alguns dos per\u00edodos de car\u00eancia mais comuns aplicam-se normalmente \u00e0s seguintes situa\u00e7\u00f5es:<\/span><\/p>\n<ol>\n<li><b> Servi\u00e7os m\u00e9dicos de base:<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">An\u00e1lises cl\u00ednicas e testes de diagn\u00f3stico.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tratamentos fisioterap\u00eauticos ou de reabilita\u00e7\u00e3o.<\/span><\/li>\n<\/ul>\n<ol start=\"2\">\n<li><b> Procedimentos espec\u00edficos:<\/b><\/li>\n<\/ol>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Cirurgias e hospitaliza\u00e7\u00f5es.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Reprodu\u00e7\u00e3o assistida, parto e cuidados pr\u00e9-natais.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Antes de subscrever um seguro de sa\u00fade, <\/span><b>\u00e9 essencial que tenha conhecimento dos tipos de per\u00edodos de car\u00eancia inclu\u00eddos na sua ap\u00f3lice<\/b><span style=\"font-weight: 400;\">, A Comiss\u00e3o deve ser consultada sobre a disponibilidade de servi\u00e7os em caso de necessidade m\u00e9dica, uma vez que esta pode afetar a disponibilidade de certos servi\u00e7os em caso de necessidade m\u00e9dica, como no caso de uma cirurgia.<\/span><\/p>\n<p><a class=\"popmake-26194\" href=\"#\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-31045 size-full\" src=\"https:\/\/pibgroupiberia.com\/wp-content\/uploads\/2016\/05\/BANNER-A.gif\" alt=\"Contacto connosco\" width=\"500\" height=\"100\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Normalmente, estes per\u00edodos de espera variam entre 6 e 10 meses, exceto no caso de quest\u00f5es de reprodu\u00e7\u00e3o assistida, que poucas seguradoras cobrem e que s\u00e3o mais longos.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Como posso saber se um trabalhador tem um per\u00edodo de qualifica\u00e7\u00e3o e o que acontece se n\u00e3o tiver?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A exist\u00eancia e a dura\u00e7\u00e3o de <\/span><b>Os per\u00edodos de car\u00eancia s\u00e3o geralmente especificados de forma clara em qualquer contrato de seguro de sa\u00fade.<\/b><span style=\"font-weight: 400;\"> \u00c9 essencial, quando uma empresa contrata um seguro de sa\u00fade para os seus trabalhadores, que estes analisem cuidadosamente os termos e condi\u00e7\u00f5es das suas ap\u00f3lices de sa\u00fade para obterem informa\u00e7\u00f5es pormenorizadas sobre estes per\u00edodos de espera.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Se um trabalhador estiver dentro do per\u00edodo de car\u00eancia, ter\u00e1 de esperar pelo fim deste per\u00edodo para poder aceder a determinados servi\u00e7os ou coberturas espec\u00edficas. Durante esse per\u00edodo, s\u00f3 estar\u00e1 coberto para as eventualidades que n\u00e3o estejam sujeitas ao per\u00edodo de car\u00eancia.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">No caso de um trabalhador necessitar de cuidados m\u00e9dicos urgentes e se encontrar dentro do per\u00edodo de elegibilidade, deve <\/span><b>contacte a sua seguradora para obter informa\u00e7\u00f5es pormenorizadas<\/b><span style=\"font-weight: 400;\"> sobre quais os servi\u00e7os dispon\u00edveis e quais os n\u00e3o compat\u00edveis durante esta fase inicial da pol\u00edtica.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que \u00e9 que seria evitar a priva\u00e7\u00e3o?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A preven\u00e7\u00e3o da escassez ou, tamb\u00e9m designada por aus\u00eancia de escassez, refere-se \u00e0 <\/span><b>n\u00e3o h\u00e1 per\u00edodos de car\u00eancia num seguro de sa\u00fade<\/b><span style=\"font-weight: 400;\">. Se uma ap\u00f3lice de seguro n\u00e3o tiver per\u00edodos de car\u00eancia, isso significa que o segurado pode aceder a todos os servi\u00e7os e coberturas desde o in\u00edcio da ap\u00f3lice, sem ter de esperar por qualquer per\u00edodo adicional.<\/span> <span style=\"font-weight: 400;\">Sim, como j\u00e1 referimos num post anterior, <\/span><a href=\"https:\/\/pibgroupiberia.com\/pt\/blogue\/e-possivel-subscrever-uma-apolice-de-seguro-de-doenca-sem-pagamento-de-carencias\/\"><span style=\"font-weight: 400;\">\u00e9 poss\u00edvel subscrever um seguro de baixa por doen\u00e7a sem lacunas<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">N\u00e3o se esque\u00e7a que o essencial \u00e9 ler atentamente as condi\u00e7\u00f5es da sua ap\u00f3lice e conhecer os per\u00edodos de car\u00eancia aplic\u00e1veis. Desta forma, pode tomar decis\u00f5es informadas e garantir que o seu seguro de doen\u00e7a est\u00e1 corretamente adaptado \u00e0s suas necessidades ou \u00e0s da sua fam\u00edlia.\u00a0<\/span><\/i><\/p>\n<p><a class=\"popmake-26194\" href=\"#\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-31045 size-full\" src=\"https:\/\/pibgroupiberia.com\/wp-content\/uploads\/2016\/05\/BANNER-A.gif\" alt=\"Contacto connosco\" width=\"500\" height=\"100\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Os cuidados de sa\u00fade s\u00e3o um aspeto fundamental das nossas vidas, e ter uma cobertura que satisfa\u00e7a as nossas expectativas e necessidades \u00e9 fundamental para manter a nossa sa\u00fade e bem-estar. <\/span><b>paz de esp\u00edrito e bem-estar.<\/b><span style=\"font-weight: 400;\"> Em <a href=\"\/pt\/\">Grupo PIB Ib\u00e9ria<\/a> trabalhamos com as melhores companhias de seguros e podemos ajud\u00e1-lo a encontrar a ap\u00f3lice com o menor n\u00famero de defici\u00eancias para o seu caso espec\u00edfico. Contacte j\u00e1 a nossa equipa e dar-lhe-emos um aconselhamento personalizado.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te ha pasado que no has podido acceder a ciertos servicios m\u00e9dicos a pesar de haber contratado un seguro de salud, porque este ten\u00eda periodos de carencia? Es una situaci\u00f3n que puede ser frustrante y preocupante cuando se necesita atenci\u00f3n m\u00e9dica especializada o un tratamiento espec\u00edfico de manera urgente. Sin duda, la espera [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":13756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":4.9,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[16,152],"tags":[],"class_list":["post-13755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulares","category-profesionales"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/13755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/comments?post=13755"}],"version-history":[{"count":1,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/13755\/revisions"}],"predecessor-version":[{"id":21349,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/13755\/revisions\/21349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media\/13756"}],"wp:attachment":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media?parent=13755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/categories?post=13755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/tags?post=13755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}