{"id":14734,"date":"2018-05-07T18:24:52","date_gmt":"2018-05-07T16:24:52","guid":{"rendered":"https:\/\/pibgroupiberia.com\/?p=5304"},"modified":"2025-05-23T10:40:50","modified_gmt":"2025-05-23T08:40:50","slug":"em-caso-de-litigio-com-a-companhia-de-seguros-o-que-devo-fazer","status":"publish","type":"post","link":"https:\/\/pibgroupiberia.com\/pt\/blog\/ante-una-discrepancia-con-la-compania-de-seguros-que-hago\/","title":{"rendered":"Se tiver um lit\u00edgio com a companhia de seguros, o que devo fazer?"},"content":{"rendered":"<p>No outro dia, est\u00e1vamos a discutir na empresa de corretagem um artigo publicado num jornal nacional sobre este assunto. O artigo centrava-se no que diz a lei, mas o funcionamento quotidiano dos seguros \u00e9 um pouco diferente. Veremos o que diz a lei e como actuamos em caso de problemas com os nossos segurados.<\/p>\n<h2>A lei sobre os contratos de seguro e as diferentes formas de apresenta\u00e7\u00e3o de um pedido de indemniza\u00e7\u00e3o<\/h2>\n<p>Quando um cliente\/segurado n\u00e3o concorda com a decis\u00e3o da seguradora, existem diferentes formas de apresentar uma reclama\u00e7\u00e3o \u00e0 seguradora. S\u00e3o elas:<\/p>\n<ol>\n<li>De acordo com o art. <em><strong>38 da Lei do contrato de seguro<\/strong><\/em>o cliente \u00ablesado\u00bb pode nomear um <strong>especialista<\/strong> para o ajudar a provar \u00e0 empresa que o segurado tem raz\u00e3o e corroborar a sua opini\u00e3o. O custo deste perito dever\u00e1 ser suportado pelo cliente. Se persistirem discrep\u00e2ncias, pode recorrer-se a um terceiro perito.<\/li>\n<li>O <strong>Servi\u00e7o de apoio ao cliente da companhia de seguros<\/strong> ou tamb\u00e9m conhecido como \u201c<em>Defesa do segurado<\/em>\u201dA reclama\u00e7\u00e3o deve ser resolvida num prazo de dois meses por todas as seguradoras. Este facto \u00e9 vinculativo para a companhia, mas n\u00e3o para o cliente, que disp\u00f5e de outras vias de recurso.<\/li>\n<li>O <strong>Dire\u00e7\u00e3o-Geral de Seguros<\/strong> disp\u00f5e igualmente de um servi\u00e7o de Defesa do Segurado, ao qual podem recorrer as pessoas que se sintam lesadas pela sua companhia de seguros.<\/li>\n<\/ol>\n<p>Para al\u00e9m disso, \u00e9 claro, haveria a <strong>vias judiciais<\/strong> que pode ser utilizado por qualquer pessoa, mas que j\u00e1 implica um custo mais elevado.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-5305\" src=\"\/wp-content\/uploads\/2018\/05\/seguro-reclamaciones.jpg\" alt=\"Seguradoras e problemas com sinistros\" width=\"950\" height=\"760\" \/><\/p>\n<h2>Corretor de seguros, porqu\u00ea?<\/h2>\n<p>Como dissemos, vimos as diferentes op\u00e7\u00f5es jur\u00eddicas que se abrem ao cliente. Todas elas implicam o consumo de recursos, sejam eles econ\u00f3micos ou tempor\u00e1rios. N\u00e3o \u00e9 por acaso que as op\u00e7\u00f5es gratuitas, como o Servi\u00e7o de Defesa do Tomador de Seguro das empresas ou a DGS, demoram muito tempo a ser resolvidas.<\/p>\n<p>\u00c9 aqui que o papel de um <a href=\"\/pt\/\">Corretagem de seguros<\/a>. Lamentavelmente, <strong>nem todas as reclama\u00e7\u00f5es s\u00e3o resolvidas \u00e0 primeira<\/strong>. H\u00e1 alturas em que um cliente pode reclamar mais danos do que os que o perito ou a empresa ir\u00e3o atribuir, h\u00e1 discrep\u00e2ncias no valor a indemnizar ou mil outras quest\u00f5es que podem correr mal.<\/p>\n<p><strong>O papel de uma empresa de corretagem \u00e9 defender o seu tomador de seguro.<\/strong>. Os corretores prestam este servi\u00e7o (n\u00f3s prestamos). <strong>sem cobrar ao cliente<\/strong>, S\u00e3o as diferentes companhias que nos pagam para lhes trazermos clientes. E, no entanto, devemos isso aos nossos segurados, a quem devemos muito dinheiro. <em>\u201cpartir-nos a cara\u201d.\u201d<\/em> quando a empresa n\u00e3o cumpre o seu dever e n\u00e3o respeita os direitos do segurado.<\/p>\n<h2>At\u00e9 onde se estende o servi\u00e7o prestado por uma empresa de corretagem?<\/h2>\n<p>Este servi\u00e7o, em caso de sinistro, implica frequentemente telefonemas para:<\/p>\n<ul>\n<li>especialistas,<\/li>\n<li>gestores de sinistros,<\/li>\n<li>corpora\u00e7\u00f5es e<\/li>\n<li>diferentes pessoas envolvidas no incidente<\/li>\n<\/ul>\n<p>para facilitar e resolver o problema do cliente. \u00c9 um trabalho que est\u00e1 feito, por assim dizer, <em>\u00abnas sombras\u00bb<\/em> (porque, em muitos casos, o cliente nem sequer o v\u00ea), mas sim o que fazemos para garantir que os pedidos de indemniza\u00e7\u00e3o s\u00e3o tratados da melhor forma poss\u00edvel.<\/p>\n<p>Como dizemos, este servi\u00e7o \u00e9 o que <strong>justifica<\/strong> <strong>que uma pol\u00edtica<\/strong> seguro de habita\u00e7\u00e3o, seguro de sa\u00fade ou uma ap\u00f3lice de f\u00e9rias da empresa ou de um trabalhador independente, <strong>\u00e9 subscrito n\u00e3o diretamente com a empresa<\/strong> (que vai varrer para o seu lado)<strong> mas com uma Corretora<\/strong> isso:<\/p>\n<ol>\n<li>Em primeiro lugar, ajuda-o a <strong>comparar ofertas<\/strong> empresas, aconselhando-o sobre as coberturas adequadas<\/li>\n<li>Depois, <strong>em caso de sinistro, ajud\u00e1-lo-\u00e1 a geri-lo.<\/strong> para que a seguradora n\u00e3o se aproveite da situa\u00e7\u00e3o.<\/li>\n<\/ol>\n<h2>Como \u00e9 que escolho um seguro que me proteja?<\/h2>\n<p>Devemos ter em conta muitos factores na escolha do nosso seguro, pois n\u00e3o \u00e9 apenas a vari\u00e1vel pre\u00e7o que \u00e9 importante: <strong>salvaguardas<\/strong>, boa gama de <strong>reparadores<\/strong>, como \u00e9 que o <strong>gest\u00e3o de sinistros<\/strong> na empresa...<\/p>\n<p>PIB Group Iberia ajuda-o a encontrar a companhia de seguros que n\u00e3o se esconde nem se afasta de si em caso de sinistro, mas que responde realmente quando precisa.<\/p>","protected":false},"excerpt":{"rendered":"<p>As companhias de seguros disp\u00f5em de Departamentos de Apoio ao Cliente, mas s\u00e3o muito lentos\u2026 Veremos como resolver os sinistros de forma r\u00e1pida<\/p>","protected":false},"author":14,"featured_media":14735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[16],"tags":[163],"class_list":["post-14734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulares","tag-decesos"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/14734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/comments?post=14734"}],"version-history":[{"count":0,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/posts\/14734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media\/14735"}],"wp:attachment":[{"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/media?parent=14734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/categories?post=14734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pibgroupiberia.com\/pt\/wp-json\/wp\/v2\/tags?post=14734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}